{"id":1330,"date":"2019-02-24T01:15:38","date_gmt":"2019-02-24T01:15:38","guid":{"rendered":"https:\/\/designed.cad.rit.edu\/vcdthesis\/?page_id=1330"},"modified":"2023-04-25T19:20:22","modified_gmt":"2023-04-25T19:20:22","slug":"vcd-thesis-gallery","status":"publish","type":"page","link":"https:\/\/designed.cad.rit.edu\/vcdthesis\/","title":{"rendered":"VCD Thesis Gallery"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"folder":[],"class_list":["post-1330","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/designed.cad.rit.edu\/vcdthesis\/wp-json\/wp\/v2\/pages\/1330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/designed.cad.rit.edu\/vcdthesis\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/designed.cad.rit.edu\/vcdthesis\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/designed.cad.rit.edu\/vcdthesis\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/designed.cad.rit.edu\/vcdthesis\/wp-json\/wp\/v2\/comments?post=1330"}],"version-history":[{"count":3,"href":"https:\/\/designed.cad.rit.edu\/vcdthesis\/wp-json\/wp\/v2\/pages\/1330\/revisions"}],"predecessor-version":[{"id":1339,"href":"https:\/\/designed.cad.rit.edu\/vcdthesis\/wp-json\/wp\/v2\/pages\/1330\/revisions\/1339"}],"wp:attachment":[{"href":"https:\/\/designed.cad.rit.edu\/vcdthesis\/wp-json\/wp\/v2\/media?parent=1330"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/designed.cad.rit.edu\/vcdthesis\/wp-json\/wp\/v2\/folder?post=1330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}